{"id":3797,"date":"2020-03-09T12:09:15","date_gmt":"2020-03-09T11:09:15","guid":{"rendered":"http:\/\/www.electrex.it\/en\/?p=3797"},"modified":"2020-03-09T17:53:37","modified_gmt":"2020-03-09T16:53:37","slug":"%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva","status":"publish","type":"post","link":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html","title":{"rendered":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva."},"content":{"rendered":"<h2><\/h2>\n<h2 style=\"text-align: center;\">Nuevas penalizaciones por energ\u00eda reactiva capacitiva.<\/h2>\n<h2 style=\"text-align: center;\">La gesti\u00f3n de la calidad de la energ\u00eda se vuelve de primera importancia.<\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-1256 aligncenter\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-News-WEB.jpg\" alt=\"Electrex -The importance of managing Power Quality and reduce the financial losses caused by disturbances\" width=\"960\" height=\"600\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-News-WEB-300x188.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-News-WEB-768x480.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-News-WEB.jpg 960w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores. El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.<\/p>\n<p>Cuando ocurre que se hay\u00a0 un consumo menor de energ\u00eda activa (por ejemplo durante la noche), es muy probable de exceder el consumo de energ\u00eda capacitiva. A todos los excesos de capacitiva que superen el l\u00edmite de un cos phi de 0,98 capacitivo se aplica una penalizaci\u00f3n de forma horaria.<\/p>\n<blockquote><p>Por consiguiente, se har\u00e1 a\u00fan m\u00e1s importante gestionar la calidad de la energ\u00eda, esto significa medir corriente y voltaje al mismo tiempo en todas la tres fases.<\/p>\n<p>Desde siempre Electrex ofrece una soluci\u00f3n avanzada para gestionar la calidad de la energ\u00eda con analizadores fijos y portables.<\/p><\/blockquote>\n<p><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d1cfcf;border-color:#d1cfcf;border-top-width:2px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-1\"><\/p>\n<p>Contactame para fichar una llamada por tel\u00e9fono y sere feliz de alludarle!<\/p>\n<p>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-color:rgba(0,188,212,0.16);--awb-bg-color-hover:rgba(0,188,212,0.16);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-margin-bottom-large:20px;--awb-width-medium:100%;--awb-width-small:100%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-person person fusion-person-center fusion-person-1 fusion-person-icon-top\" style=\"--awb-pic-style-color:#000000;--awb-pic-borderradius:50%;--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-social-box-border-top:0px;--awb-social-box-border-right:0px;--awb-social-box-border-bottom:0px;--awb-social-box-border-left:0px;--awb-social-box-border-color:var(--awb-color3);--awb-social-box-border-color-hover:var(--awb-color4);--awb-social-box-colors-hover:rgba(232,232,232,0.8);--awb-social-icon-boxed-colors:#e8e8e8;--awb-social-icon-colors:#bebdbd;--awb-social-icon-colors-hover:rgba(190,189,189,0.8);\"><div class=\"person-shortcode-image-wrapper\"><div class=\"person-image-container hover-type-zoomin person-rounded-overflow\" style=\"-webkit-border-radius:50%;-moz-border-radius:50%;border-radius:50%;border:1px solid #bababa;-webkit-border-radius:50%;-moz-border-radius:50%;border-radius:50%;\"><a href=\"https:\/\/www.linkedin.com\/in\/cristian-gobbi-210318173\" target=\"_self\"><img decoding=\"async\" class=\"person-img img-responsive wp-image-3793\" width=\"200\" height=\"200\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2020\/03\/Cristian-Gobbi.jpg\" alt=\"Cristian Gobbi\" \/><\/a><\/div><\/div><div class=\"person-desc\"><div class=\"person-author\"><div class=\"person-author-wrapper\"><span class=\"person-name\">Cristian Gobbi<\/span><span class=\"person-title\">Ventas<\/span><\/div><div class=\"fusion-social-networks\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-youtube awb-icon-youtube custom\" aria-label=\"fusion-youtube\" href=\"https:\/\/www.youtube.com\/user\/ELECTREXAkse\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"YouTube\" title=\"YouTube\" data-toggle=\"tooltip\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin custom\" aria-label=\"fusion-linkedin\" href=\"https:\/\/www.linkedin.com\/in\/cristian-gobbi-210318173\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"LinkedIn\" title=\"LinkedIn\" data-toggle=\"tooltip\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp awb-icon-whatsapp custom\" aria-label=\"fusion-whatsapp\" href=\"https:\/\/wa.me\/393314353529\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"Whatsapp\" title=\"Whatsapp\" data-toggle=\"tooltip\"><\/a><\/div><\/div><\/div><div class=\"person-content fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-border-color:#d6d6d6;--awb-border-style:solid;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-margin-bottom-large:20px;--awb-width-medium:100%;--awb-width-small:100%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3392-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3392\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/3797#wpcf7-f3392-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3392\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3392-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Tu Nombre <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label> Tu Correo <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> Tu Tel\u00e9fono<span class=\"wpcf7-form-control-wrap\" data-name=\"Tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"Tel\" \/><\/span> <\/label><br \/>\n<label> Tu Mensaje<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envia\" \/>\n<\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output fusion-alert-capitalize awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Close\">&times;<\/button><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d1cfcf;border-color:#d1cfcf;border-top-width:2px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><\/p>\n<h3>PRECIO DE LA MALA CALIDAD DE LA ENERGIA<\/h3>\n<p>El estado ideal de una carga tendr\u00eda una constante magnitud y forma de onda de voltaje de frecuencia. Sin embargo , esto no es posible en instalaciones reales (cortes, impedancia no-cero, etc.). Las consecuencias de la mala calidad de la energ\u00eda incluyen:<\/p>\n<ul>\n<li>Fallos inesperados de la fuente de alimentaci\u00f3n (interruptores que saltan, fusibile que soplan).<\/li>\n<li>Disfuncionamento\u00a0 y fallos de equipos.<\/li>\n<li>Calentamiento del equipo (transformadores, motores, \u2026) que conduce a su reducci\u00f3n de vida.<\/li>\n<li>Da\u00f1os a equipos sensibles (PC, sistemas de control de l\u00edneas de producci\u00f3n, etc.).<\/li>\n<li>Interferencias de comunicaci\u00f3n electr\u00f3nicas.<\/li>\n<li>Aumento de p\u00e9rdidas de sistema.<\/li>\n<li>Necesidad de sobredimensionar las instalaciones para hacer frente a la tensi\u00f3n el\u00e9ctrica adicional con el consiguiente aumento de los costes de instalaci\u00f3n y funcionamiento y la consiguiente mayor huella de carbono.<\/li>\n<li>Las sanciones impuestas por los servicios p\u00fablicos porque el sitio contamina demasiado la red de suministro.<\/li>\n<li>Rechazo de conexi\u00f3n de nuevos sitios porque el sitio contaminar\u00eda demasiado la red de suministro.<\/li>\n<\/ul>\n<p><strong>La evaluaci\u00f3n de la calidad de la fuente de alimentaci\u00f3n tiene en cuenta principalmente dos par\u00e1metros:<\/strong><\/p>\n<ul>\n<li>la continuidad del suministro el\u00e9ctrico, entendida como ninguna interrupci\u00f3n en el suministro de electricidad.<\/li>\n<li>la calidad de tensi\u00f3n, entendida como la calidad de la forma de onda (amplitud, frecuencia, variaciones, etc.).<\/li>\n<\/ul>\n<p><strong>Hay muchos factores que afectan la calidad de la electricidad. Algunos de los m\u00e1s importantes son:\u00a0<\/strong><\/p>\n<ul>\n<li>factores relacionados con la utilidad (gesti\u00f3n y funcionamiento de la red, mantenimiento, \u2026)<\/li>\n<li>factores relacionados con el usuario final (fallos en la instalaci\u00f3n del usuario, ruido emitido en la red, -&#8230;)<\/li>\n<li>independiente (factores ambientales, fen\u00f3menos meteorol\u00f3gicos, da\u00f1os causados por terceros, &#8230;)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Monitorizazi\u00f3n de la calidad de la energ\u00eda y de los arm\u00f3nicos<\/h3>\n<p>La monitorizaci\u00f3n de la calidad de la energ\u00eda es ya un servicio proporcionado por los servicios de red a sus clientes principales (grandes usuarios de energ\u00eda industriales y comerciales). De todos modos muchos estudios han demostrado que la mayor\u00eda de los problemas ocurren dentro de las instalaciones del cliente. Este hecho significa que el monitoreo de la calidad de la energ\u00eda despu\u00e9s del medidor de utilidad proporciona una gama de beneficios tanto para la utilidad y el usuario-final. Esto es a\u00fan m\u00e1s cierto en un escenario en el que muchos usuarios-finales son tambi\u00e9n productores de energ\u00eda.<\/p>\n<p>El monitoreo de la Calidad de Potencia permitir\u00e1 detectar las fuentes\/causas de los problemas dentro de la red del usuario-final.\u00a0La soluci\u00f3n ser\u00eda eliminar la fuente o hacer inmune a la instalaci\u00f3n de la mala calidad de la energ\u00eda.\u00a0Ambas soluciones suelen costar mucho menos que los da\u00f1os potenciales que pueden derivarse.<\/p>\n<p>De todos modos todav\u00eda un gran n\u00famero de final-usuarios no invierten en este campo e ignoran la eficiencia que puede derivar de la soluci\u00f3n de los problemas con la calidad de la energ\u00eda mala.<\/p>\n<p>Adem\u00e1s de la falta de sensibilizaci\u00f3n informativa entre los interesados, una de las principales razones es que la mayor parte del costo de una mala calidad de la energ\u00eda a menudo se oculta. Por lo tanto, un sistema de monitoreo es uno de los primeros pasos hacia la optimizaci\u00f3n de la Calidad de Energ\u00eda.<\/p>\n<p><strong>Como podemos ayudarles<\/strong><\/p>\n<p>Nuestro Analizador de Energ\u00eda de Calidad El\u00e9ctrica &amp; Gestor de Datos Electrex de <strong><a href=\"\/en\/category\/products\/energy-analyzer-a-web-data-manager\">la familia de productos Kilo PQ<\/a><\/strong>, adem\u00e1s de medir y gestionar el consumo de energ\u00eda, est\u00e1n dise\u00f1ados para controlar la calidad de la energ\u00eda y controlar si la instalaci\u00f3n y el equipo manejan correctamente las cargas de trabajo.<\/p>\n<p>Los dispositivos Kilo PQ se utilizan para::<\/p>\n<ul>\n<li>el registro de eventos PQ<\/li>\n<li>mantenimento preventivo<\/li>\n<li>detecci\u00f3n de problemas de PQ<\/li>\n<li>campa\u00f1as de medici\u00f3n de PQ para per\u00edodos espec\u00edficos definidos por el usuario<\/li>\n<li>seguimiento del cumplimiento de las normas PQ o de las normas de servicio<\/li>\n<\/ul>\n<p><strong>Calidad de energ\u00eda (Clase S &#8211; EN 61000-4-30): Registro de eventos<\/strong><\/p>\n<p>EL\u00a0Kilo D6 PQ\u00a0detecta y registra varios eventos con una resoluci\u00f3n de un ciclo (con fecha\/ hora * de cada evento, tipo de evento, fase implicada, duraci\u00f3n, min \/ valor m\u00e1ximo alcanzado durante el evento y clasificaci\u00f3n <a href=\"http:\/\/www.eurelectric.org\/\">UNIPEDE<\/a>) \u00fatil para controlar la calidad de la energ\u00eda (funciones relacionadas tambi\u00e9n con las normas EN 50160 y EN 61000-4-30 para la clase S). Los par\u00e1metros para definir eventos anormales son programables.<\/p>\n<p><strong>Tipos de eventos:<\/strong><\/p>\n<ul>\n<li>Picos de voltaje<\/li>\n<li>Ca\u00edda de voltaje<\/li>\n<li>Sobre corriente (y su direcci\u00f3n)<\/li>\n<li>Interrupci\u00f3n<\/li>\n<\/ul>\n<div id=\"attachment_1264\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1264\" class=\"wp-image-1264 size-large\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-1024x572.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Events\" width=\"1024\" height=\"572\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-300x168.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-768x429.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-1024x572.jpg 1024w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1264\" class=\"wp-caption-text\">(*) Fecha\/hora expresada en horas, minutos, segundos y milisegundos referidos a los instrumentos&#8217; (hora local). En la tabla se muestran tambi\u00e9n algunos registros funcionales como los relacionados con la configuraci\u00f3n.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>DETALLES GR\u00c1FICOS DEL EVENTO<\/strong><\/p>\n<p><strong><a href=\"\/en\/category\/products\/energy-analyzer-a-web-data-manager\">El\u00a0Kilo D6 PQ<\/a><\/strong>\u00a0incluye la funci\u00f3n llamada\u00a0&#8220;event&#8217;s graphic detail&#8221; che permite de registrar y mostrar las tendencias de inizio y final del evento con un marco de tiempo\u00a0(para principio y fin) de un segundo (programable).<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1258 aligncenter\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Overcurrent-PH3-graph.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Overcurrent-PH3-graph\" width=\"828\" height=\"479\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Overcurrent-PH3-graph-300x174.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Overcurrent-PH3-graph-768x444.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Overcurrent-PH3-graph.jpg 828w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1259 aligncenter\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Dip-PH1-graph.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Dip-PH1-graph\" width=\"827\" height=\"492\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Dip-PH1-graph-300x178.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Dip-PH1-graph-768x457.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Dip-PH1-graph.jpg 827w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1260 aligncenter\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Swell-PH1-graph.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Swell-PH1-graph\" width=\"824\" height=\"482\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Swell-PH1-graph-300x175.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Swell-PH1-graph-768x449.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Swell-PH1-graph.jpg 824w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/p>\n<p><strong>CALENDARIO DE ACTIVIDADES Y CUADRO DEL UNIPEDE<\/strong><\/p>\n<p>El\u00a0Kilo D6 PQ\u00a0puede mostrar un calendario de sucesi\u00f3n de eventos<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1261 aligncenter\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Events-Timeline\" width=\"823\" height=\"431\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-300x157.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-768x402.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline.jpg 823w\" sizes=\"(max-width: 823px) 100vw, 823px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1262\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-Swell.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Events-Timeline-Swell\" width=\"825\" height=\"432\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-Swell-300x157.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-Swell-768x402.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-Timeline-Swell.jpg 825w\" sizes=\"(max-width: 825px) 100vw, 825px\" \/><\/p>\n<p>y mantiene un diagrama de distribuci\u00f3n de eventos basado en el % del par\u00e1metro considerado en relaci\u00f3n con su valor de referencia y duraci\u00f3n, de acuerdo con los dictados de la UNIPEDE (International Union of Producers and Distributors of Energy).<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1263\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-UNIPEDE-table.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-UNIPEDE-table\" width=\"867\" height=\"505\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-UNIPEDE-table-300x175.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-UNIPEDE-table-768x447.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-UNIPEDE-table.jpg 867w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><\/p>\n<p>Ejemplo: en la \u00faltima columna de la tabla de aqu\u00ed abajo, la S1 denota un Voltaje Swell con una duraci\u00f3n entre 10 y 500 Ms (v\u00e9ase la tabla UNIPEDE de arriba), mientras que el X2 denota una Tensi\u00f3n Dip inferior al 5% del valor nominal de tensi\u00f3n con una duraci\u00f3n entre los 10 y 200 Ms.<\/p>\n<p><img decoding=\"async\" class=\"size-large wp-image-1264\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-1024x572.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Events\" width=\"1024\" height=\"572\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-300x168.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-768x429.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events-1024x572.jpg 1024w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Events.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>CAMPA\u0147A DE MEDICI\u00d3N<\/strong><\/p>\n<p>Con el \u00a0<strong><a href=\"\/en\/category\/products\/energy-analyzer-a-web-data-manager\">Kilo D6 PQ<\/a><\/strong>\u00a0es posible configurar la campa\u00f1a de medici\u00f3n para registrar, en la memoria built-in, los diversos par\u00e1metros con un muestreo programable.<\/p>\n<p>Ejemplo de una campa\u00f1a diaria de medici\u00f3n de las tensiones de 3 fases:<\/p>\n<p><img decoding=\"async\" class=\"size-large wp-image-1265\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-1024x912.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Modbus-logger-Harmonics\" width=\"1024\" height=\"912\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-300x267.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-768x684.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-1024x912.jpg 1024w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-large wp-image-1266\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-2-1024x910.jpg\" alt=\"Kilo D6 PQ Electrex-Power-Quality-Modbus-logger-Harmonics-2\" width=\"1024\" height=\"910\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-2-300x267.jpg 300w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-2-768x682.jpg 768w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-2-1024x910.jpg 1024w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2015\/04\/Electrex-Power-Quality-Modbus-logger-Harmonics-2.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En cuanto a la calidad de la tensi\u00f3n, el Kilo PQ se refiere a la norma europea EN 50160, que distingue las diferentes perturbaciones en fen\u00f3menos continuos y tensiones.<\/p>\n<p><strong>Los fen\u00f3menos continuos incluyen:<\/strong><\/p>\n<ul>\n<li>variaciones de frecuencia<\/li>\n<li>variaciones de la tenci\u00f3n de alimentaci\u00f3n<\/li>\n<li>desequilibrio de voltaje<\/li>\n<li>voltajes arm\u00f3nicos<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Los eventos de voltaje incluyen:<\/strong><\/p>\n<ul>\n<li>interrupciones de la tensi\u00f3n de alimentaci\u00f3n<\/li>\n<li>ca\u00eddas de voltaje<\/li>\n<li>s\u00faper-elevaciones a frecuencia industrial y tensi\u00f3n transitoria<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Origen de perturbaciones<\/strong><\/p>\n<p>Los ruidos est\u00e1n siempre presentes en las redes el\u00e9ctricas y son producidos principalmente por:<\/p>\n<ul>\n<li>fallo en la l\u00ednea de suministro del usuario o en las otras l\u00edneas conectadas a \u00e9l<\/li>\n<li>fallos de las redes internas de clientes<\/li>\n<li>corrientes de inrush de transformadores y condensadores<\/li>\n<li>cargas r\u00e1pidamente variables y corrientes de pico de los motores<\/li>\n<li>cargas no lineales<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Indicadores de calidad de tensi\u00f3n. Qu\u00e9 medir.<\/strong><\/p>\n<p>La calidad de la tensi\u00f3n de control examina los siguientes par\u00e1metros:<\/p>\n<ul>\n<li>amplitud y r\u00e1pidos \/ cambios lentos de voltaje<\/li>\n<li>ca\u00eddas de voltaje<\/li>\n<li>arm\u00f3nicos<\/li>\n<li>disequilibrio de voltaje<\/li>\n<\/ul>\n<p>Al ejecutar un programa de monitoreo de calidad el\u00e9ctrica, es importante considerar que la red cambia continuamente. Los dispositivos de medici\u00f3n tradicionales no son adecuados para el seguimiento de cargas no lineales, ya que el equipo utilizado debe medir en RMS Verdadero y especificar el rango de medici\u00f3n arm\u00f3nica \u00fanica.<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3>POWER QUALITY &amp; Wi-Fi WEB DATA MANAGER<\/h3>\n<p><strong>Las gamas Kilo net D6 y 96, Giga Box y Libra Panel<\/strong><\/p>\n<p>Las revolucionarias gamas de Power Quality Energy Analyzer &amp; Wi-Fi Data Manager para la monitorizaci\u00f3n de los par\u00e1metros el\u00e9ctricos, la gesti\u00f3n de la electricidad (cantidad y calidad), el gas, el agua, el aire comprimido, los par\u00e1metros ambientales y de proceso y la automatizaci\u00f3n energ\u00e9tica en el sector industrial y terciario. Aptos tambi\u00e9n para usos intensos. Wifi, Ethernet, radio E-Wi, ExpBus, RS485, NFC. Versiones modulares, transportables y Plug &amp; Play.<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h3>REDES DE MONITORIZACI\u00d3N Y GESTI\u00d3N ENERG\u00c9TICA<\/h3>\n<p>Las redes de monitorizaci\u00f3n Electrex son la soluci\u00f3n ideal para las auditor\u00edas energ\u00e9ticas, la monitorizaci\u00f3n continua (por ejemplo, ISO 50001) y para proyectos de eficiencia energ\u00e9tica (por ejemplo, Directiva 2012-27-UE y certificados blancos o certificados de eficiencia energ\u00e9tica). Los sistemas Electrex son modulares y pueden ampliarse con el paso del tiempo gracias a las m\u00faltiples posibilidades de conexi\u00f3n de los instrumentos (wifi, RS485, E-Wi, ExpBus, Ethernet, NFC) y de visualizaci\u00f3n y gesti\u00f3n de los datos recopilados. Con un \u00fanico sistema se pueden controlar todos los recursos energ\u00e9ticos (electricidad, gas, agua, etc.), los par\u00e1metros ambientales relacionados con estos (temperatura, humedad, luminosidad, CO2, etc.) y los de proceso (aire comprimido, calor\u00edas, nivel, estado, etc.); medir el tiempo real de funcionamiento de los servicios utilizando un \u00fanico reloj de referencia; gestionar procesos de Automatizaci\u00f3n energ\u00e9tica &#8211; Industria 4.0 (automatizar la gesti\u00f3n de encendidos \/ apagados, ajustes autom\u00e1ticos, telegesti\u00f3n, alarmas y muchas otras posibilidades). Todo ello para alcanzar el objetivo principal: reducir los costes energ\u00e9ticos optimizando la producci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h3>QUI\u00c9NES SOMOS<\/h3>\n<p><img decoding=\"async\" class=\"size-full wp-image-2620 alignright\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2004\/08\/electrex-20-years-experience-1.png\" alt=\"\" width=\"283\" height=\"283\" srcset=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2004\/08\/electrex-20-years-experience-1-66x66.png 66w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2004\/08\/electrex-20-years-experience-1-150x150.png 150w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2004\/08\/electrex-20-years-experience-1-200x200.png 200w, https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2004\/08\/electrex-20-years-experience-1.png 283w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>Desde 1993, en Electrex dise\u00f1amos, desarrollamos y comercializamos, tanto en Italia como en otros pa\u00edses, instrumentos y software para la medida, el ahorro y la gesti\u00f3n del consumo y la producci\u00f3n de energ\u00eda.<\/p>\n<p>Las soluciones de Electrex se utilizan en aplicaciones del campo de la eficiencia energ\u00e9tica y la automatizaci\u00f3n energ\u00e9tica en el sector industrial, terciario, civil, de las administraciones p\u00fablicas y las fuentes renovables, permitiendo un retorno de la inversi\u00f3n a corto plazo.<\/p>\n<p>Electrex, una de las primeras empresas en operar en estos sectores, ha adquirido a lo largo de los a\u00f1os una vasta experiencia y habilidades de las que muy pocas empresas pueden presumir. Con m\u00e1s del 40% del personal dedicado a la Investigaci\u00f3n y el Desarrollo, demostramos nuestra fuerte vocaci\u00f3n hacia la innovaci\u00f3n y la mejora continua para adelantarnos a las necesidades de nuestros clientes.<\/p>\n<p>Supervisamos el producto desde la fase de dise\u00f1o hasta el servicio de asistencia posventa y nuestra empresa, flexible y din\u00e1mica, es cada vez m\u00e1s apreciada por colaboradores locales e internacionales.<\/p>\n<div class=\"bfd-single-download\" id=\"bfd-single-download-1874\">\n\t\t<div class=\"bfd-single-row\">\n\n\t\t\t\t <div class=\"bfd-column bfd-single-button-container\">\n\t\t \t\t\t\t \t\t<a href=\"https:\/\/www.electrex.it\/en\/bfd_download\/electrex-redes-de-monitorizacion-y-gestion-energetica\" title=\"Download Electrex Company Profile in Spanish - Redes de monitorizaci\u00f3n y gesti\u00f3n energ\u00e9tica\" class=\"bfd-svg-container bfd-single-download-btn\" download >\n\t\t\t\t \t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" version=\"1.1\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-6.000000, -5.000000)\" fill=\"currentColor\"><path d=\"M26.7 21.7L21.7 21.7 21.7 5 18.3 5 18.3 21.7 13.3 21.7 20 28.3 26.7 21.7 26.7 21.7ZM6.7 31.7L6.7 35 33.3 35 33.3 31.7 6.7 31.7 6.7 31.7Z\"\/><\/g><\/g><\/svg>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t <\/div>\n\t\t <div class=\"bfd-column\">\n\t\t \t<a href=\"https:\/\/www.electrex.it\/en\/bfd_download\/electrex-redes-de-monitorizacion-y-gestion-energetica\" title=\"Download Electrex Company Profile in Spanish - Redes de monitorizaci\u00f3n y gesti\u00f3n energ\u00e9tica\" class=\"bfd-download-meta\" download >\n\t\t\t \t<p class=\"bfd-download-title\"><strong>Electrex Company Profile in Spanish - Redes de monitorizaci\u00f3n y gesti\u00f3n energ\u00e9tica<\/strong><\/p>\n\t\t\t \t\t\t\t \t<p class=\"bfd-bottom-zero\">\n\t\t\t \t\t<small>\n\t\t\t \t\t\tType: pdf\t\t\t \t\t<\/small>\n\t\t\t \t<\/p>\n\t\t\t <\/a>\n\t\t<\/div>\n\t\t <div class=\"bfd-column bfd-mime-col\">\n\t\t \t<object data=\"https:\/\/www.electrex.it\/en\/wp-content\/plugins\/better-file-download\/public\/partials\/..\/..\/colour-svg-file-types\/pdf.svg\" type=\"image\/svg+xml\" class=\"bfd-svg bfd-icon-img bfd-icon-single\"><\/object>\n\n\t\t<\/div>\n\t<\/div>\n<\/div> <!-- \/.single-download -->\n<br\/>\n\n<p><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d1cfcf;border-color:#d1cfcf;border-top-width:2px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-2\"><\/p>\n<p>Contactame para fichar una llamada por tel\u00e9fono y sere feliz de alludarle!<\/p>\n<p>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-color:rgba(0,188,212,0.16);--awb-bg-color-hover:rgba(0,188,212,0.16);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-margin-bottom-large:20px;--awb-width-medium:100%;--awb-width-small:100%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-person person fusion-person-center fusion-person-2 fusion-person-icon-top\" style=\"--awb-pic-style-color:#000000;--awb-pic-borderradius:50%;--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-social-box-border-top:0px;--awb-social-box-border-right:0px;--awb-social-box-border-bottom:0px;--awb-social-box-border-left:0px;--awb-social-box-border-color:var(--awb-color3);--awb-social-box-border-color-hover:var(--awb-color4);--awb-social-box-colors-hover:rgba(232,232,232,0.8);--awb-social-icon-boxed-colors:#e8e8e8;--awb-social-icon-colors:#bebdbd;--awb-social-icon-colors-hover:rgba(190,189,189,0.8);\"><div class=\"person-shortcode-image-wrapper\"><div class=\"person-image-container hover-type-zoomin person-rounded-overflow\" style=\"-webkit-border-radius:50%;-moz-border-radius:50%;border-radius:50%;border:1px solid #bababa;-webkit-border-radius:50%;-moz-border-radius:50%;border-radius:50%;\"><a href=\"https:\/\/www.linkedin.com\/in\/cristian-gobbi-210318173\" target=\"_self\"><img decoding=\"async\" class=\"person-img img-responsive wp-image-3793\" width=\"200\" height=\"200\" src=\"http:\/\/www.electrex.it\/en\/wp-content\/uploads\/2020\/03\/Cristian-Gobbi.jpg\" alt=\"Cristian Gobbi\" \/><\/a><\/div><\/div><div class=\"person-desc\"><div class=\"person-author\"><div class=\"person-author-wrapper\"><span class=\"person-name\">Cristian Gobbi<\/span><span class=\"person-title\">Ventas<\/span><\/div><div class=\"fusion-social-networks\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-youtube awb-icon-youtube custom\" aria-label=\"fusion-youtube\" href=\"https:\/\/www.youtube.com\/user\/ELECTREXAkse\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"YouTube\" title=\"YouTube\" data-toggle=\"tooltip\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin custom\" aria-label=\"fusion-linkedin\" href=\"https:\/\/www.linkedin.com\/in\/cristian-gobbi-210318173\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"LinkedIn\" title=\"LinkedIn\" data-toggle=\"tooltip\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp awb-icon-whatsapp custom\" aria-label=\"fusion-whatsapp\" href=\"https:\/\/wa.me\/393314353529\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#bebdbd;font-size:16px;\" data-placement=\"top\" data-title=\"Whatsapp\" title=\"Whatsapp\" data-toggle=\"tooltip\"><\/a><\/div><\/div><\/div><div class=\"person-content fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-border-color:#d6d6d6;--awb-border-style:solid;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-margin-bottom-large:20px;--awb-width-medium:100%;--awb-width-small:100%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3392-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3392\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/3797#wpcf7-f3392-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3392\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3392-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Tu Nombre <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label> Tu Correo <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> Tu Tel\u00e9fono<span class=\"wpcf7-form-control-wrap\" data-name=\"Tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"Tel\" \/><\/span> <\/label><br \/>\n<label> Tu Mensaje<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envia\" \/>\n<\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output fusion-alert-capitalize awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Close\">&times;<\/button><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:10px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d1cfcf;border-color:#d1cfcf;border-top-width:2px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevas penalizaciones por energ\u00eda reactiva capacitiva. La gesti\u00f3n de la calidad de la energ\u00eda se vuelve de primera importancia. La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores. El nuevo sistema de peajes el\u00e9ctricos  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":1598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[678],"tags":[680,681,679,92],"class_list":["post-3797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-calidad-de-la-energia","tag-circular-3-2020","tag-blog","tag-electrex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology<\/title>\n<meta name=\"description\" content=\"La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.electrex.it\/en\/blog\/\ud83c\uddea\ud83c\uddf8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology\" \/>\n<meta property=\"og:description\" content=\"La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.electrex.it\/en\/blog\/\ud83c\uddea\ud83c\uddf8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\" \/>\n<meta property=\"og:site_name\" content=\"Electrex - the energy saving technology\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-09T11:09:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-09T16:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Skender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Skender\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\"},\"author\":{\"name\":\"Skender\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/#\\\/schema\\\/person\\\/c95fac169422d7c263ca94c4cd838b11\"},\"headline\":\"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva.\",\"datePublished\":\"2020-03-09T11:09:15+00:00\",\"dateModified\":\"2020-03-09T16:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\"},\"wordCount\":3193,\"image\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/Electrex-Power-Quality-News-WEB.jpg\",\"keywords\":[\"Calidad de la Energ\u00eda\",\"Circular 3\\\/2020\",\"blog\",\"Electrex\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\",\"url\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\",\"name\":\"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/Electrex-Power-Quality-News-WEB.jpg\",\"datePublished\":\"2020-03-09T11:09:15+00:00\",\"dateModified\":\"2020-03-09T16:53:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/#\\\/schema\\\/person\\\/c95fac169422d7c263ca94c4cd838b11\"},\"description\":\"La Circular 3\\\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage\",\"url\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/Electrex-Power-Quality-News-WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/Electrex-Power-Quality-News-WEB.jpg\",\"width\":960,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/blog\\\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/\",\"name\":\"Electrex - the energy saving technology\",\"description\":\"Since 1993 Electrex designs, develops, manufactures and markets, Made in Italy, instruments and software for energy measurement,  management and control.  The Electrex solutions are used in the energy efficiency and Energy Automation applications, for the industrial, commercial, public, civil, and renewable energy sectors.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/#\\\/schema\\\/person\\\/c95fac169422d7c263ca94c4cd838b11\",\"name\":\"Skender\",\"sameAs\":[\"http:\\\/\\\/www.electrex.it\\\/en\"],\"url\":\"https:\\\/\\\/www.electrex.it\\\/en\\\/author\\\/skender\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology","description":"La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.electrex.it\/en\/blog\/\ud83c\uddea\ud83c\uddf8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html","og_locale":"en_US","og_type":"article","og_title":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology","og_description":"La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.","og_url":"https:\/\/www.electrex.it\/en\/blog\/\ud83c\uddea\ud83c\uddf8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html","og_site_name":"Electrex - the energy saving technology","article_published_time":"2020-03-09T11:09:15+00:00","article_modified_time":"2020-03-09T16:53:37+00:00","og_image":[{"width":960,"height":600,"url":"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg","type":"image\/jpeg"}],"author":"Skender","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Skender","Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#article","isPartOf":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html"},"author":{"name":"Skender","@id":"https:\/\/www.electrex.it\/en\/#\/schema\/person\/c95fac169422d7c263ca94c4cd838b11"},"headline":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva.","datePublished":"2020-03-09T11:09:15+00:00","dateModified":"2020-03-09T16:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html"},"wordCount":3193,"image":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage"},"thumbnailUrl":"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg","keywords":["Calidad de la Energ\u00eda","Circular 3\/2020","blog","Electrex"],"articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html","url":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html","name":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva. - Electrex - the energy saving technology","isPartOf":{"@id":"https:\/\/www.electrex.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage"},"image":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage"},"thumbnailUrl":"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg","datePublished":"2020-03-09T11:09:15+00:00","dateModified":"2020-03-09T16:53:37+00:00","author":{"@id":"https:\/\/www.electrex.it\/en\/#\/schema\/person\/c95fac169422d7c263ca94c4cd838b11"},"description":"La Circular 3\/2020 de la Comisi\u00f3n Nacional de los Mercados ha actualizado las normas inherentes a la calidad de la energ\u00eda para los grandes consumidores.El nuevo sistema de peajes el\u00e9ctricos entrar\u00e1 en funcionamiento el 1 de noviembre de 2020.","breadcrumb":{"@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#primaryimage","url":"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg","contentUrl":"https:\/\/www.electrex.it\/en\/wp-content\/uploads\/2011\/05\/Electrex-Power-Quality-News-WEB.jpg","width":960,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.electrex.it\/en\/blog\/%f0%9f%87%aa%f0%9f%87%b8-calidad-de-la-energia-nuevas-penalizaciones-por-energia-reactiva-capacitiva.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.electrex.it\/en\/"},{"@type":"ListItem","position":2,"name":"&#x1f1ea;&#x1f1f8; Calidad de la Energ\u00eda: nuevas penalizaciones por energ\u00eda reactiva capacitiva."}]},{"@type":"WebSite","@id":"https:\/\/www.electrex.it\/en\/#website","url":"https:\/\/www.electrex.it\/en\/","name":"Electrex - the energy saving technology","description":"Since 1993 Electrex designs, develops, manufactures and markets, Made in Italy, instruments and software for energy measurement,  management and control.  The Electrex solutions are used in the energy efficiency and Energy Automation applications, for the industrial, commercial, public, civil, and renewable energy sectors.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.electrex.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.electrex.it\/en\/#\/schema\/person\/c95fac169422d7c263ca94c4cd838b11","name":"Skender","sameAs":["http:\/\/www.electrex.it\/en"],"url":"https:\/\/www.electrex.it\/en\/author\/skender"}]}},"_links":{"self":[{"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/posts\/3797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/comments?post=3797"}],"version-history":[{"count":10,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/posts\/3797\/revisions"}],"predecessor-version":[{"id":3807,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/posts\/3797\/revisions\/3807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/media\/1598"}],"wp:attachment":[{"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/media?parent=3797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/categories?post=3797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.electrex.it\/en\/wp-json\/wp\/v2\/tags?post=3797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}